{"id":32746,"date":"2022-12-01T05:23:09","date_gmt":"2022-12-01T10:23:09","guid":{"rendered":"http:\/\/getibogaine.com\/?p=13031"},"modified":"2026-05-25T21:00:16","modified_gmt":"2026-05-26T01:00:16","slug":"andere-pflanzen-mit-anti-suchtig-potential","status":"publish","type":"post","link":"https:\/\/getibogaine.com\/de\/andere-pflanzen-mit-anti-suchtig-potential\/","title":{"rendered":"Pflanzen mit Anti-Addikationspotential"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Seit Jahrhunderten hat sich die Menschheit mit dem verheerenden Griff der Sucht auseinandergesetzt. Vom Reiz von Substanzen bis zu den zwanghaften Verhaltensweisen, die uns verzehren, ist die Reichweite von Sucht gro\u00df und ihre Auswirkungen tiefgreifend. Aber was ist, wenn die Natur den Schl\u00fcssel zum Brechen h\u00e4tte?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Artikel befasst sich mit der faszinierenden Welt der Pflanzen mit s\u00fcchtig machendem Potenzial und erkundet die bemerkenswerten botanischen Verb\u00fcndeten, die Hoffnung auf die \u00dcberwindung von Suchtproblemen bieten. Reisen Sie durch die wissenschaftlichen Beweise und die traditionelle Weisheit, die das Potenzial dieser nat\u00fcrlichen Heilmittel beleuchten, und untersuchen Sie ihre Wirkmechanismen und die vielversprechende Forschung, die sich weiter entwickelt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bereiten Sie sich darauf vor, eine neue Perspektive auf Sucht und die m\u00e4chtige Rolle zu entdecken, die Pflanzen auf unserem Weg zur Heilung und Genesung spielen k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Angesichts der Opioidkrise in der Welt ist es keine \u00dcberraschung, dass die Erforschung nat\u00fcrlicher und alternativer Methoden der <a title=\"Ketamine Addiction Treatment With Iboga\" href=\"https:\/\/getibogaine.com\/de\/?p=33510\">Sucht behandeln<\/a> hat dramatisch zugenommen.&nbsp;<\/p>\n\n\n\n<h4 id=\"h-the-following-are-some-other-plants-that-have-anti-addictive-potential\" class=\"wp-block-heading\">Im Folgenden finden Sie einige andere Pflanzen, die ein Anti-S\u00fcchtigen-Potenzial haben:<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ein vielversprechender Untersuchungsbereich ist die Verwendung von Pflanzen zur Behandlung von Suchtkrankheiten, insbesondere im Vergleich zu traditionellen Optionen der westlichen Medizin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Obwohl nicht alle Pflanzen wissenschaftlich getestet wurden, haben sich einige als Behandlung f\u00fcr Sucht als vielversprechend erwiesen. Erkunden Sie in diesem Artikel andere Pflanzen, die zur Bek\u00e4mpfung der Opioidabh\u00e4ngigkeit (oder einer Drogenabh\u00e4ngigkeit) beitragen k\u00f6nnen.<\/p>\n\n\n\n<div class=\"wp-block-rank-math-toc-block\" id=\"rank-math-toc\"><h2>Table of Contents<\/h2><nav><ul><li><a href=\"#h-1-ashwagandha\">1. Ashwagandha<\/a><\/li><li><a href=\"#h-2-brahmi\">2. Brahmi<\/a><\/li><li><a href=\"#h-3-catnip\">3. Katzenminze<\/a><\/li><li><a href=\"#h-4-skullcap\">4. Sch\u00e4delkappe<\/a><\/li><li><a href=\"#h-5-salvia\">5. Salvia<\/a><\/li><li><a href=\"#h-6-reishi\">6. Reishi<\/a><\/li><li><a href=\"#h-7-the-ayahuasca-vine-banisteriopsis-caapi\">7. Die Ayahuasca-Rebe banisteriopsis caapi<\/a><\/li><li><a href=\"#h-8-blue-lotus-nymphaea-caerulea\">8. Blauer Lotus Nymphaea caerulea.<\/a><\/li><li><a href=\"#h-conclusion\">Fazit: Pflanzen mit Anti-Addiktivpotenzial<\/a><\/li><\/ul><\/nav><\/div>\n\n\n\n<h2 id=\"h-1-ashwagandha\" class=\"wp-block-heading\">1. Ashwagandha<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ashwagandha gilt als Adaptogen, was bedeutet, dass es Ihrem K\u00f6rper hilft, ein gesundes Gleichgewicht aufrechtzuerhalten. Es wurde auch gezeigt, dass Ashwagandha entz\u00fcndungshemmende und antioxidative Wirkungen hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Pflanze kann auf verschiedene Arten verwendet werden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>als Tee (1 TL getrocknete Wurzel pro Tasse) oder Tinktur (1 ml pro 10 Pfund K\u00f6rpergewicht). Einfach kochendes Wasser in das getrocknete Kraut geben, 5-10 Minuten ziehen lassen, abseihen und trinken!<\/li>\n\n\n\n<li>Pulverform: Um ein Pulver aus Ihrem trockenen Kraut herzustellen, geben Sie es einfach in eine K\u00fcchenmaschine mit 1 EL Kokos\u00f6l oder Ghee, bis Sie die gew\u00fcnschte Konsistenz erhalten. Sie k\u00f6nnen dies zum Beispiel auf Joghurt oder Smoothies streuen!<\/li>\n<\/ul>\n\n\n\n<h2 id=\"h-2-brahmi\" class=\"wp-block-heading\">2. Brahmi<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Brahmi ist eines der am weitesten verbreiteten Kr\u00e4uter im Ayurveda und wird als Nerventonikum verwendet. Es ist auch bekannt f\u00fcr seine F\u00e4higkeit, Angstzust\u00e4nde, Schlaflosigkeit, Ged\u00e4chtnisverlust, Depressionen und Stress zu behandeln.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es hat sich gezeigt, dass das Kraut anti-abh\u00e4ngige Eigenschaften hat, indem es bei Entzugssymptomen verschiedener Suchtmittel wie Alkohol, Drogen und Tabakprodukten hilft.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Brahmi wird seit der Antike zur Behandlung von Herzkrankheiten, Diabetes und Krebs eingesetzt. Es kann topisch angewendet oder intern auf der Grundlage der Behandlung eingenommen werden, die behandelt werden muss.<\/p>\n\n\n\n<h2 id=\"h-3-catnip\" class=\"wp-block-heading\">3. Katzenminze<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Catnip oder Nepeta Cataria ist ein mehrj\u00e4hriges Kraut in der Familie Mint. Es wurde zuerst in Europa und Asien angebaut. Seitdem hat es sich jedoch nach Nordamerika ausgebreitet.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Katzenminze kann fast \u00fcberall wachsen, wo andere Mitglieder ihrer Gattung wachsen, einschlie\u00dflich nasser Wiesen, Stra\u00dfenr\u00e4nder, Gr\u00e4ben und sogar G\u00e4rten (obwohl sie oft als Unkraut betrachtet werden).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend die meisten Menschen Catnip nur ein Kraut mit einigen interessanten Eigenschaften f\u00fcr Katzen (und sogar Menschen) betrachten, deuten mehrere Studien darauf hin, dass diese Pflanze m\u00f6glicherweise eine Anti-Sucht-Behandlung hat.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/getibogaine.com\/de\/therapeutischen-gemeinschaften-von-ibogain\/\"><img decoding=\"async\" src=\"http:\/\/getibogaine.com\/wp-content\/uploads\/2022\/11\/The-Importance-of-ibogaine-Therapeutic-Communities.jpg\" alt=\"The Importance of ibogaine Therapeutic Communities\" style=\"aspect-ratio:4\/3;object-fit:cover\" title=\"\"><\/a><figcaption class=\"wp-element-caption\">Lesen Sie auch: <a title=\"The Importance of Ibogaine Therapeutic Communities\" href=\"https:\/\/getibogaine.com\/de\/therapeutischen-gemeinschaften-von-ibogain\/\">Die Bedeutung von Ibogain-Therapeutischen Gemeinschaften<\/a><\/figcaption><\/figure>\n\n\n\n<h2 id=\"h-4-skullcap\" class=\"wp-block-heading\">4. Sch\u00e4delkappe<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Sch\u00e4delkappe (Scutellaria lateriflora), auch bekannt als gew\u00f6hnliche Sch\u00e4delkappe oder blaue Sch\u00e4delkappe, ist ein Kraut, das seit Tausenden von Jahren in der traditionellen chinesischen Medizin verwendet wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist bekannt, dass Skullcap anti-s\u00fcchtig machende Eigenschaften hat und bei der Behandlung von Depressionen und Angstzust\u00e4nden hilfreich sein kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als Tee: Mischen Sie 2 Teel\u00f6ffel getrocknete Sch\u00e4deldecke mit hei\u00dfem Wasser; 10 Minuten ziehen; Vor dem Trinken das Pflanzenmaterial abseihen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als Tinktur: 1 Teel\u00f6ffel getrocknete Sch\u00e4deldecke mit 2 Unzen Wodka oder Getreidealkohol mischen (80 Proof); Lassen Sie es zwei Wochen lang sitzen und zittern Sie t\u00e4glich; Wenn Sie einsatzbereit sind, das Pflanzenmaterial herausziehen<\/p>\n\n\n\n<h2 id=\"h-5-salvia\" class=\"wp-block-heading\">5. Salvia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Gattung Salvia enth\u00e4lt \u00fcber 700 Arten, aber nur wenige werden medizinisch verwendet. Die am h\u00e4ufigsten verwendeten Kr\u00e4uter in dieser Kategorie sind gew\u00f6hnlicher Salbei, Gartensalbei und dalmatinischer Salbei.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die beiden letztgenannten Pflanzen werden seit Hunderten von Jahren zur Behandlung verschiedener Gesundheitszust\u00e4nde eingesetzt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salvia ist seit der Antike als Halluzinogen bekannt; Es wurde einst angenommen, dass es sich um ein Kraut handelt, das Visionen hervorrufen und Sie unsichtbar machen kann, wenn Sie auf seinen Bl\u00e4ttern kauen. Es ist in einigen Kulturen auch als Salbei, Gemeiner Salbei und Gartensalbei bekannt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salvia wird manchmal von Teenagern und jungen Erwachsenen, die nicht mit anderen Medikamenten wie LSD oder Pilzen (Psilocybin) in Verbindung gebracht werden, mit Tabak gemischt oder allein zu Freizeitzwecken geraucht.<\/p>\n\n\n\n<h2 id=\"h-6-reishi\" class=\"wp-block-heading\">6. Reishi<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Reishi ist ein Begriff f\u00fcr den Pilz Ganoderma lucidum. Es wird seit Jahrhunderten in der chinesischen Kr\u00e4utermedizin verwendet und hat nachweislich entz\u00fcndungshemmende und antioxidative Eigenschaften.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Pilz ist auch als Ling Zhi in China und Ganoderma lucidum im Westen bekannt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Pilz wurde zur Behandlung einer Vielzahl von Erkrankungen verwendet, darunter Krebs, Asthma, Diabetes und Hepatitis.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Einige <a title=\"Studies on the Use of Ibogaine to Treat Heroin Withdrawal\" href=\"http:\/\/getibogaine.com\/studies-on-the-use-of-ibogaine-to-treat-heroin-withdrawal\/\">Studien deuten darauf hin, dass es bei der Behandlung n\u00fctzlich sein kann<\/a> auch Alzheimer-Krankheit; Es gibt jedoch noch nicht gen\u00fcgend Beweise, um mit Sicherheit abzuschlie\u00dfen.<\/p>\n\n\n\n<h2 id=\"h-7-the-ayahuasca-vine-banisteriopsis-caapi\" class=\"wp-block-heading\">7. Die Ayahuasca-Rebe banisteriopsis caapi<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Ayahuasca-Rebe (Banisteriopsis caapi) ist ein stark psychedelisches Gebr\u00e4u, das in schamanischen Ritualen in S\u00fcdamerika verwendet wird.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es enth\u00e4lt Harmin, das als MAOI (Monoaminoxidase-Inhibitor) wirkt und vermutlich f\u00fcr die halluzinogene Wirkung von Ayahuasca verantwortlich ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ayahuasca wurde zur Behandlung von Alkoholismus und Drogenabh\u00e4ngigkeit sowie anderen psychischen Erkrankungen wie PTBS, Depressionen, Angstzust\u00e4nden und Schlafst\u00f6rungen eingesetzt.<\/p>\n\n\n\n<h2 id=\"h-8-blue-lotus-nymphaea-caerulea\" class=\"wp-block-heading\">8. Blauer Lotus Nymphaea caerulea.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der blaue Lotus Nymphaea caerulea ist eine Pflanze mit sedativen und euphorischen Wirkungen. Es wird in vielen Kulturen als Freizeitdroge verwendet, kann aber Halluzinationen und andere Nebenwirkungen verursachen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist in vielen L\u00e4ndern illegal; Es ist jedoch sehr sch\u00f6n, wenn man es aus der N\u00e4he betrachtet! Das blaue Leuchten seiner Blumen ist unter hellen Lichtern spektakul\u00e4r; Achten Sie nur darauf, sie von Flammen oder offenen Flammen fernzuhalten, die den Pollen entz\u00fcnden k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Blauer Lotus geh\u00f6rt zur Familie der Seerose (Nymphaeaceae) zusammen mit anderen Wasserpflanzen wie White Lotus (Nelumbo nucifera) und \u00e4gyptischer Blauer Lotus (Nelumbo lutea).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Pflanzen sind nicht nur wundersch\u00f6ne Blumen, die im Laufe der Geschichte in religi\u00f6sen Zeremonien oder dekorativen Displays verwendet werden, sondern haben auch einige potenzielle medizinische Anwendungen, wie z. B. die Behandlung von Krebssymptomen wie \u00dcbelkeit durch Chemotherapie.<\/p>\n\n\n\n<h3 id=\"h-takeaway\" class=\"wp-block-heading\">Imbiss:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Verwendung von Heilpflanzen als antiaddiktive Hilfsmittel verdient mehr Aufmerksamkeit von der wissenschaftlichen Gemeinschaft und den Klinikern.<\/p>\n\n\n\n<h2 id=\"h-conclusion\" class=\"wp-block-heading\">Fazit: Pflanzen mit Anti-Addiktivpotenzial<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wir hoffen, dass dieser Artikel hilfreich und informativ ist. Wir glauben, dass das Verst\u00e4ndnis der Wissenschaft hinter der Sucht uns helfen kann, unser Verhalten besser zu verstehen und fundierte Entscheidungen dar\u00fcber zu treffen, wie wir bewusster leben k\u00f6nnen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie mehr \u00fcber andere Pflanzen mit Anti-Addiktiv-Potenzial erfahren m\u00f6chten, lesen Sie unseren Blog-Beitrag f\u00fcr Sucht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die F\u00e4higkeit bestimmter Pflanzen, jemandem zu helfen, eine Sucht zu beenden, ist ein vielversprechender Forschungsbereich. Es gibt viele M\u00f6glichkeiten, dies zu tun, aber eine M\u00f6glichkeit, die f\u00fcr einige Menschen funktioniert, besteht darin, eine Pflanze mit anti-s\u00fcchtig machenden Eigenschaften zu verwenden.<\/p>\n\n\n\n<h4 id=\"h-helpful-resources\" class=\"wp-block-heading\">hilfreiche Ressourcen<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Nationales Institut f\u00fcr Drogenmissbrauch (NIDA):<\/strong> <a style=\"color: #ff9900\" href=\"https:\/\/nida.nih.gov\/\" target=\"_blank\" rel=\"noopener\">Nida<\/a> ist eine von der Regierung finanzierte Forschungsorganisation, die Informationen und Ressourcen zu Sucht und Drogenmissbrauch bereitstellt. Ihre Website bietet Ressourcen, die speziell auf die Pandemie zugeschnitten sind, einschlie\u00dflich Informationen zu Telemedizin- und Online-Support-Gruppen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Verwaltung von Drogenmissbrauch und psychische Gesundheit (SAMHSA):<\/strong> <a style=\"color: #ff9900\" href=\"https:\/\/www.samhsa.gov\/\" target=\"_blank\" rel=\"noopener\">Samhsa<\/a> ist eine Regierungsbeh\u00f6rde, die Informationen und Ressourcen zu Sucht und psychischer Gesundheit liefert. Ihre Website bietet Ressourcen, die speziell auf die Pandemie zugeschnitten sind, einschlie\u00dflich einer nationalen Helpline f\u00fcr Personen, die mit Suchtproblemen oder psychischen Problemen zu k\u00e4mpfen haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. <a style=\"color: #ff9900\" href=\"https:\/\/www.aa.org\/\" target=\"_blank\" rel=\"noopener\">Anonyme Alkoholiker<\/a> (aa):<\/strong> AA ist eine Selbsthilfegruppe f\u00fcr Personen, die mit Alkoholabh\u00e4ngigkeit zu k\u00e4mpfen haben. AA hat viele seiner Meetings online verschoben, um Einzelpersonen eine sichere und zug\u00e4ngliche M\u00f6glichkeit zu bieten, mit anderen in Kontakt zu treten, die ihre K\u00e4mpfe verstehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4. <a style=\"color: #ff9900\" href=\"https:\/\/www.na.org.au\/multi\/\" target=\"_blank\" rel=\"noopener\">Bet\u00e4ubungsmittel anonym<\/a> (na):<\/strong> NA ist eine Selbsthilfegruppe f\u00fcr Personen, die mit Drogenabh\u00e4ngigkeit zu k\u00e4mpfen haben. Wie AA hat NA viele seiner Meetings online verschoben, um Einzelpersonen eine sichere und zug\u00e4ngliche M\u00f6glichkeit zu bieten, mit anderen in Kontakt zu treten, die ihre K\u00e4mpfe verstehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5. Fachkr\u00e4fte f\u00fcr psychische Gesundheit:<\/strong> Psychiater wie Therapeuten und Berater k\u00f6nnen Menschen, die w\u00e4hrend der Pandemie mit Sucht zu k\u00e4mpfen haben, individuell unterst\u00fctzen und unterst\u00fctzen. Viele psychiatrische Fachkr\u00e4fte bieten Teletherapie, eine telefonische oder \u00fcber Videokonferenzen durchgef\u00fchrte Therapieform an.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit Jahrhunderten hat sich die Menschheit mit dem verheerenden Griff der Sucht auseinandergesetzt. Vom Reiz von Substanzen bis zu den [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":32747,"comment_status":"open","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2711],"tags":[],"class_list":["post-32746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produkte-rund-um-iboga"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/getibogaine.com\/wp-content\/uploads\/2022\/12\/the-plant.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/getibogaine.com\/de\/wp-json\/wp\/v2\/posts\/32746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/getibogaine.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/getibogaine.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/getibogaine.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/getibogaine.com\/de\/wp-json\/wp\/v2\/comments?post=32746"}],"version-history":[{"count":2,"href":"https:\/\/getibogaine.com\/de\/wp-json\/wp\/v2\/posts\/32746\/revisions"}],"predecessor-version":[{"id":47020,"href":"https:\/\/getibogaine.com\/de\/wp-json\/wp\/v2\/posts\/32746\/revisions\/47020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/getibogaine.com\/de\/wp-json\/wp\/v2\/media\/32747"}],"wp:attachment":[{"href":"https:\/\/getibogaine.com\/de\/wp-json\/wp\/v2\/media?parent=32746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/getibogaine.com\/de\/wp-json\/wp\/v2\/categories?post=32746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/getibogaine.com\/de\/wp-json\/wp\/v2\/tags?post=32746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}