{"id":32676,"date":"2024-05-27T11:48:06","date_gmt":"2024-05-27T15:48:06","guid":{"rendered":"http:\/\/getibogaine.com\/?p=12807"},"modified":"2026-06-19T11:13:24","modified_gmt":"2026-06-19T15:13:24","slug":"impacto-de-la-ibogaina-2026","status":"publish","type":"post","link":"https:\/\/getibogaine.com\/es\/impacto-de-la-ibogaina-2026\/","title":{"rendered":"C\u00f3mo Ibogaine impactar\u00eda al mundo en 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El <strong>impacto de la iboga\u00edna<\/strong> en el mundo podr\u00eda marcar un punto de inflexi\u00f3n este a\u00f1o. Esta poderosa medicina vegetal, venerada durante mucho tiempo por su potencial transformador, est\u00e1 preparada para alterar el panorama de la salud global. Si bien a\u00fan est\u00e1 envuelta en controversias y restricciones legales, su influencia en el tratamiento de la adicci\u00f3n, nuestra comprensi\u00f3n de la conciencia e incluso el tejido de nuestra sociedad es innegable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este art\u00edculo profundiza en el impacto potencial de la iboga\u00edna en <strong>2026<\/strong>, examinando sus posibles beneficios y riesgos. Explorar bien la evidencia cient\u00edfica, las consideraciones \u00e9ticas y los desaf\u00edos que se avecinan, a medida que la iboga\u00edna contin\u00faa su viaje hacia la aceptaci\u00f3n general.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prep\u00e1rese para ser desafiado, inspirado y tal vez incluso un poco inc\u00f3modo mientras exploramos el profundo impacto que esta antigua medicina podr\u00eda tener en nuestro mundo en el pr\u00f3ximo a\u00f1o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El viaje de Iboga: del descubrimiento a la moderna terapia de iboga\u00edna<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized\"><img decoding=\"async\" src=\"http:\/\/getibogaine.com\/wp-content\/uploads\/2024\/05\/cc122158-efc6-415e-841f-bada9ded5179.png\" alt=\"One of many Iboga Plantations in Cameroon | Ibogaine&#039;s impact\" style=\"width:526px;height:auto\" title=\"\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La historia de Iboga y su componente activo, Ibogaine, es un viaje fascinante desde el uso tradicional en rituales cham\u00e1nicos africanos hasta un potencial avance en el tratamiento moderno de la adicci\u00f3n. Esta publicaci\u00f3n explora la evoluci\u00f3n de Iboga, centr\u00e1ndose en su uso medicinal en la terapia de iboga\u00edna hoy en d\u00eda, abordando aspectos importantes como los ensayos cl\u00ednicos, los resultados del tratamiento y los desaf\u00edos en curso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El descubrimiento de Iboga<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Iboga, una de las muchas drogas psicoactivas, es un arbusto nativo de \u00c1frica central, espec\u00edficamente en regiones como Gab\u00f3n, Camer\u00fan y Congo. La corteza de la ra\u00edz de la planta de Tabernan Iboga ha sido utilizada durante siglos por la religi\u00f3n Bwiti en las ceremonias espirituales para inducir experiencias psicoactivas profundas. Estos rituales a menudo involucraban altas dosis de corteza de ra\u00edz de iboga, proporcionando importantes conocimientos psicol\u00f3gicos y curaci\u00f3n emocional.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Introducci\u00f3n de Ibogaine al Oeste<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A mediados del siglo XX, los cient\u00edficos occidentales comenzaron a interesarse por las propiedades psicoactivas de la iboga\u00edna, el principal alcaloide de Iboga. Las primeras investigaciones se centraron en su potencial para inducir estados visionarios intensos, pero no fue hasta la d\u00e9cada de 1960 que se descubrieron sus propiedades contra la adicci\u00f3n. Los informes anecd\u00f3ticos sugirieron que la iboga\u00edna podr\u00eda reducir los antojos y los s\u00edntomas de abstinencia asociados con la dependencia de opi\u00e1ceos y otras formas de abuso de sustancias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el art\u00edculo de hoy, discutiremos;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Educaci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El uso del f\u00e1rmaco contra la adicci\u00f3n iboga\u00edna en el tratamiento de la drogodependencia y tambi\u00e9n en el tratamiento de la adicci\u00f3n y el PTSD sigue siendo controvertido. Si bien hay muchos estudios que muestran su efectividad en estas \u00e1reas, no est\u00e1 aprobado para el tratamiento por ninguna autoridad m\u00e9dica. Existe una necesidad urgente de ensayos cl\u00ednicos controlados para determinar la seguridad y efectividad de la iboga\u00edna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n sigue siendo ilegal en muchos pa\u00edses de todo el mundo debido a sus reconocidas propiedades alucin\u00f3genas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iboga\u00edna ha demostrado potencial en el tratamiento del abuso de drogas y la dependencia de drogas, con propiedades antiadictivas prometedoras y una resoluci\u00f3n sostenida de los s\u00edndromes de abstinencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si est\u00e1 interesado en explorar la posibilidad de dejar los medicamentos con Ibogaine, pero le preocupa su estatus legal o la falta de apoyo profesional de m\u00e9dicos o psic\u00f3logos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recomendamos buscar en un retiro de ibogaine donde puedan ofrecerle toda la informaci\u00f3n que necesita, as\u00ed como la atenci\u00f3n individualizada a lo largo de su experiencia, as\u00ed como proveedores en l\u00ednea como <a href=\"https:\/\/getibogaine.com\/es\/\" rel=\"noopener noreferrer\">www.getibogaine.com<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Rehabilitaci\u00f3n de tratamiento de iboga\u00edna<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Otra \u00e1rea importante en la que la iboga\u00edna tendr\u00e1 impacto es la rehabilitaci\u00f3n a trav\u00e9s del tratamiento de iboga\u00edna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien todav\u00eda no est\u00e1 claro exactamente c\u00f3mo <a href=\"https:\/\/getibogaine.com\/es\/adiccion-al-suboxone\/\" rel=\"noopener noreferrer\">Ibogaine trabaja sobre la adicci\u00f3n<\/a> y otros problemas de salud mental, ha mostrado resultados prometedores en personas con una variedad de adicciones. Los resultados del tratamiento de iboga\u00edna para varios trastornos por abuso de sustancias se han discutido ampliamente, destacando sus beneficios potenciales y peligros pr\u00e1cticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de la adicci\u00f3n a la hero\u00edna, parece haber ayudado a las personas con alcohol, metanfetamina y adicciones a la coca\u00edna, as\u00ed como con trastorno por uso de opi\u00e1ceos (OUD). Tambi\u00e9n son notables el manejo de la dependencia de opi\u00e1ceos y el potencial de la iboga\u00edna como terapia para la desintoxicaci\u00f3n de opi\u00e1ceos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n ayuda a algunas personas con trastornos de depresi\u00f3n y ansiedad como el trastorno obsesivo-compulsivo (TOC). Adem\u00e1s, la iboga\u00edna ha demostrado potencial para aliviar los s\u00edntomas de abstinencia de opi\u00e1ceos, prevenir la reca\u00edda y reducir los antojos de drogas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicho esto, no todos responden bien a la terapia de iboga\u00edna, en particular, aquellos que tienen condiciones neurol\u00f3gicas preexistentes como <a href=\"http:\/\/getibogaine.com\/ibogaine-a-promising-new-treatment-for-parkinsons-disease\/\" rel=\"noopener noreferrer\">enfermedad de Parkinson<\/a> o esquizofrenia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, si usted es alguien que responde favorablemente al protocolo de tratamiento, es posible que pueda usar iboga\u00edna por per\u00edodos m\u00e1s largos que cuando se somete a programas de rehabilitaci\u00f3n tradicionales que no incluyen este compuesto en absoluto o que simplemente ofrezcan una peque\u00f1a cantidad junto con otros medicamentos como la naltrexona o la metadona\/buprenorfina, que tienen como objetivo reducir los antojos sin eliminarlos por completo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo tanto, se permite a los usuarios un tiempo libre de su sustancia\u00a0de abuso mientras reciben tratamiento\u00a0a trav\u00e9s de sesiones de asesoramiento, mientras reciben el apoyo de amigos\/familiares durante este per\u00edodo dif\u00edcil en el que est\u00e1n tratando no solo de superar su h\u00e1bito, sino que tambi\u00e9n aprenden a vivir de manera diferente sin drogas\/alcohol en sus vidas una vez que hayan completado su estad\u00eda en las instalaciones de rehabilitaci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ensayos cl\u00ednicos tempranos e investigaci\u00f3n<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized\"><img decoding=\"async\" src=\"http:\/\/getibogaine.com\/wp-content\/uploads\/2024\/05\/bd61ecdc-a296-4e93-8678-9bf8f4109b7a.png\" alt=\"Ibogaine&#039;s impact\" style=\"width:606px;height:auto\" title=\"\"><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ensayo cl\u00ednico inicial en las d\u00e9cadas de 1980 y 1990 proporcion\u00f3 resultados prometedores, demostrando el potencial de las iboga\u00ednas en el tratamiento de la adicci\u00f3n, en particular el trastorno por uso de opi\u00e1ceos. Los estudios mostraron que las dosis \u00fanicas orales de iboga\u00edna podr\u00edan reducir significativamente los s\u00edntomas de abstinencia de opi\u00e1ceos y los antojos, convirti\u00e9ndola en una herramienta potencial para la desintoxicaci\u00f3n de opi\u00e1ceos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, estos ensayos cl\u00ednicos tambi\u00e9n destacaron la necesidad de precauci\u00f3n. Se encontr\u00f3 que la ingesti\u00f3n de iboga\u00edna conlleva riesgos, incluidos las arritmias card\u00edacas y la prolongaci\u00f3n del intervalo QT inducida por f\u00e1rmacos, lo que podr\u00eda provocar complicaciones de salud graves. Estos hallazgos enfatizaron la importancia de la supervisi\u00f3n m\u00e9dica y el control card\u00edaco durante los tratamientos de iboga\u00edna.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Disponibilidad de ensayos cl\u00ednicos<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Terapia de iboga\u00edna moderna<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de los riesgos, la terapia de iboga\u00edna ha seguido ganando tracci\u00f3n como tratamiento alternativo para la adicci\u00f3n a las drogas. Las cl\u00ednicas modernas de iboga\u00edna se establecen en pa\u00edses donde el uso de iboga\u00edna es legal, ofreciendo programas de tratamiento estructurados para personas que luchan contra la adicci\u00f3n a los opi\u00e1ceos y otros trastornos por uso de sustancias.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">mecanismo de acci\u00f3n<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La iboga\u00edna funciona interactuando con varios sistemas de neurotransmisores en el cerebro. Act\u00faa sobre los receptores NMDA, los transportadores de serotonina y los receptores de opi\u00e1ceos, lo que ayuda a restablecer la qu\u00edmica del cerebro. Esta interacci\u00f3n reduce los antojos de drogas y alivia los s\u00edntomas de abstinencia, lo que brinda una ventana de oportunidad para que los pacientes se liberen de la dependencia de las drogas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Therapeutic Potential and Challenges<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los resultados del tratamiento con iboga\u00edna han demostrado que puede ser eficaz para reducir la abstinencia de opi\u00e1ceos y prevenir la reca\u00edda. Los pacientes a menudo informan reducciones significativas en los antojos y una mejor sensaci\u00f3n de bienestar despu\u00e9s de someterse a una terapia de iboga\u00edna. Sin embargo, el tratamiento no est\u00e1 exento de desaf\u00edos:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><p><strong>Toxicidad y potencial terap\u00e9utico<\/strong>: Determinar el equilibrio entre las dosis efectivas y las dosis t\u00f3xicas de iboga\u00edna sigue siendo un desaf\u00edo. Las concentraciones de iboga\u00edna deben monitorearse cuidadosamente para evitar efectos adversos.<\/p><\/li>\n\n\n\n<li><p><strong>Supervisi\u00f3n m\u00e9dica<\/strong>: El riesgo de efectos secundarios graves, como las arritmias card\u00edacas y la prolongaci\u00f3n del QT, requiere que el tratamiento con iboga\u00edna se realice bajo estricta supervisi\u00f3n m\u00e9dica.<\/p><\/li>\n\n\n\n<li><p><strong>M\u00e1s investigaci\u00f3n<\/strong>: Se necesitan m\u00e1s ensayos cl\u00ednicos para comprender completamente el potencial terap\u00e9utico y el perfil de seguridad de la iboga\u00edna. Esto incluye estudiar sus efectos a largo plazo e interacciones con otros medicamentos.<\/p><\/li>\n\n\n\n<li><p><strong>Obst\u00e1culos regulatorios<\/strong>: En muchos pa\u00edses, la iboga\u00edna se clasifica como una sustancia controlada, limitando su disponibilidad para uso cl\u00ednico. La promoci\u00f3n de m\u00e1s investigaciones y cambios en las pol\u00edticas regulatorias est\u00e1 en curso para hacer que la terapia de iboga\u00edna sea m\u00e1s accesible.\u00a0<\/p><\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Actitudes gubernamentales hacia la iboga\u00edna<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En el futuro, el mundo podr\u00eda ser diferente de lo que es ahora, y eso no se debe solo a los avances en tecnolog\u00eda y viajes espaciales. Tambi\u00e9n es porque para entonces, la iboga\u00edna puede ser legalizada para su uso como medicina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cambio de paradigma de los medicamentos a los medicamentos hace toda la diferencia: aunque las personas que consumen drogas no son necesariamente malas personas, tienden a ser estigmatizadas por la sociedad en general; este estigma puede hacer que la recuperaci\u00f3n sea dif\u00edcil e incluso peligrosa para aquellos que buscan tratamiento de adicci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al tratar la iboga\u00edna como cualquier otro medicamento (es decir, con regulaciones estrictas), los gobiernos podr\u00edan ayudar a reducir este estigma y garantizar que los usuarios tengan acceso a la atenci\u00f3n adecuada cuando m\u00e1s lo necesiten, lo que significar\u00eda que menos personas mueran por sobredosis de opi\u00e1ceos cada a\u00f1o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Actitudes p\u00fablicas sobre la iboga\u00edna<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las actitudes p\u00fablicas son importantes porque el futuro de Ibogaine depende de su popularidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si las personas tienen miedo de usar iboga\u00edna porque piensan que es peligrosa o un tratamiento milagroso, \u00bfc\u00f3mo podemos esperar que se acepte la iboga\u00edna como un tratamiento convencional para la adicci\u00f3n?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La verdad es que se necesita hacer m\u00e1s investigaci\u00f3n antes de que tengamos una idea de los efectos a largo plazo de la iboga\u00edna, pero una cosa es cierta: muchas personas creen en este potencial de drogas y quieren que tenga \u00e9xito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos creen que la iboga\u00edna debe ser prohibida o regulada antes de que est\u00e9 disponible para el p\u00fablico. Este grupo incluye a muchos farmac\u00e9uticos y m\u00e9dicos que temen que no se haya realizado suficiente investigaci\u00f3n sobre su perfil de seguridad (o la falta de \u00e9l).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Creo que la iboga\u00edna podr\u00eda tener un impacto positivo en el mundo si se usara m\u00e1s ampliamente, pero hay obst\u00e1culos reales para eso:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p>La droga es ilegal en muchos pa\u00edses. Esto evita que las personas lo tomen legalmente, lo que hace que sea m\u00e1s probable que lo tomen ilegalmente.<\/p><\/li>\n\n\n\n<li><p>Es caro producir y distribuir una sustancia como esta, por lo que el costo del tratamiento es alto tanto para pacientes como para hospitales\/cl\u00ednicas\/etc., lo que los hace reacios a ofrecer estos tratamientos como parte de sus servicios regulares.<\/p><\/li>\n\n\n\n<li><p>Es dif\u00edcil para los usuarios recreativos que quieren probar ibogaina porque no tienen forma de obtenerla excepto a trav\u00e9s de canales ilegales (y no pueden saber si lo que est\u00e1n obteniendo es genuino). Y dado que esos canales no est\u00e1n regulados y no brindan ninguna garant\u00eda sobre los procedimientos de seguridad o control de calidad&#8230; \u00a1puede ver a d\u00f3nde llevar\u00eda esto!<\/p><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque ha habido algunos desarrollos prometedores en los \u00faltimos a\u00f1os (como el aumento de la financiaci\u00f3n de la investigaci\u00f3n), todav\u00eda no est\u00e1 disponible como tratamiento m\u00e9dico en la mayor\u00eda de los pa\u00edses, e incluso cuando las personas logran obtenerlo en otro lugar, se enfrentan a problemas legales al traerlo de regreso a casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Creo que necesitamos m\u00e1s investigaci\u00f3n sobre tratamientos alternativos para la adicci\u00f3n antes de tomar grandes decisiones sobre si deber\u00eda estar disponible a nivel mundial o no.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El impacto de la iboga\u00edna en el mundo podr\u00eda marcar un punto de inflexi\u00f3n este a\u00f1o. Esta poderosa medicina vegetal, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":32677,"comment_status":"open","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[609],"tags":[],"class_list":["post-32676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-como-funciona-la-ibogaina"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/getibogaine.com\/wp-content\/uploads\/2022\/11\/How-ibogaine-would-impact-the-world-in-2023.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/getibogaine.com\/es\/wp-json\/wp\/v2\/posts\/32676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/getibogaine.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/getibogaine.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/getibogaine.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/getibogaine.com\/es\/wp-json\/wp\/v2\/comments?post=32676"}],"version-history":[{"count":2,"href":"https:\/\/getibogaine.com\/es\/wp-json\/wp\/v2\/posts\/32676\/revisions"}],"predecessor-version":[{"id":48789,"href":"https:\/\/getibogaine.com\/es\/wp-json\/wp\/v2\/posts\/32676\/revisions\/48789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/getibogaine.com\/es\/wp-json\/wp\/v2\/media\/32677"}],"wp:attachment":[{"href":"https:\/\/getibogaine.com\/es\/wp-json\/wp\/v2\/media?parent=32676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/getibogaine.com\/es\/wp-json\/wp\/v2\/categories?post=32676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/getibogaine.com\/es\/wp-json\/wp\/v2\/tags?post=32676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}